{"id":11,"count":266,"description":"","link":"https:\/\/www.biobasedpress.eu\/nl\/tag\/duurzaamheid\/","name":"Duurzaamheid","slug":"duurzaamheid","taxonomy":"post_tag","meta":[],"yoast_head":"<title>Duurzaamheid Archives - Bio Based Press<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.biobasedpress.eu\/nl\/tag\/duurzaamheid\/\" \/>\n<meta property=\"og:locale\" content=\"nl_NL\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Duurzaamheid Archives - Bio Based Press\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.biobasedpress.eu\/nl\/tag\/duurzaamheid\/\" \/>\n<meta property=\"og:site_name\" content=\"Bio Based Press\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@biobasedpress\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/tag\\\/duurzaamheid\\\/\",\"url\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/tag\\\/duurzaamheid\\\/\",\"name\":\"Duurzaamheid Archives - Bio Based Press\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/#website\"},\"inLanguage\":\"nl-NL\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/#website\",\"url\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/\",\"name\":\"Bio Based Press\",\"description\":\"Discovering another society through sustainability and innovation\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"nl-NL\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/#organization\",\"name\":\"Bio Based Press\",\"url\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"nl-NL\",\"@id\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.biobasedpress.eu\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/BBP_logo_klein.png\",\"contentUrl\":\"https:\\\/\\\/www.biobasedpress.eu\\\/wp-content\\\/uploads\\\/2014\\\/03\\\/BBP_logo_klein.png\",\"width\":287,\"height\":287,\"caption\":\"Bio Based Press\"},\"image\":{\"@id\":\"https:\\\/\\\/www.biobasedpress.eu\\\/nl\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pages\\\/Biobased-Society\\\/158982974234328\",\"https:\\\/\\\/x.com\\\/biobasedpress\",\"http:\\\/\\\/nl.linkedin.com\\\/groups\\\/Biobased-Society-4543631\"]}]}<\/script>","yoast_head_json":{"title":"Duurzaamheid Archives - Bio Based Press","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.biobasedpress.eu\/nl\/tag\/duurzaamheid\/","og_locale":"nl_NL","og_type":"article","og_title":"Duurzaamheid Archives - Bio Based Press","og_url":"https:\/\/www.biobasedpress.eu\/nl\/tag\/duurzaamheid\/","og_site_name":"Bio Based Press","twitter_card":"summary_large_image","twitter_site":"@biobasedpress","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.biobasedpress.eu\/nl\/tag\/duurzaamheid\/","url":"https:\/\/www.biobasedpress.eu\/nl\/tag\/duurzaamheid\/","name":"Duurzaamheid Archives - Bio Based Press","isPartOf":{"@id":"https:\/\/www.biobasedpress.eu\/nl\/#website"},"inLanguage":"nl-NL"},{"@type":"WebSite","@id":"https:\/\/www.biobasedpress.eu\/nl\/#website","url":"https:\/\/www.biobasedpress.eu\/nl\/","name":"Bio Based Press","description":"Discovering another society through sustainability and innovation","publisher":{"@id":"https:\/\/www.biobasedpress.eu\/nl\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.biobasedpress.eu\/nl\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"nl-NL"},{"@type":"Organization","@id":"https:\/\/www.biobasedpress.eu\/nl\/#organization","name":"Bio Based Press","url":"https:\/\/www.biobasedpress.eu\/nl\/","logo":{"@type":"ImageObject","inLanguage":"nl-NL","@id":"https:\/\/www.biobasedpress.eu\/nl\/#\/schema\/logo\/image\/","url":"https:\/\/www.biobasedpress.eu\/wp-content\/uploads\/2014\/03\/BBP_logo_klein.png","contentUrl":"https:\/\/www.biobasedpress.eu\/wp-content\/uploads\/2014\/03\/BBP_logo_klein.png","width":287,"height":287,"caption":"Bio Based Press"},"image":{"@id":"https:\/\/www.biobasedpress.eu\/nl\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Biobased-Society\/158982974234328","https:\/\/x.com\/biobasedpress","http:\/\/nl.linkedin.com\/groups\/Biobased-Society-4543631"]}]}},"_links":{"self":[{"href":"https:\/\/www.biobasedpress.eu\/nl\/wp-json\/wp\/v2\/tags\/11","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.biobasedpress.eu\/nl\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.biobasedpress.eu\/nl\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.biobasedpress.eu\/nl\/wp-json\/wp\/v2\/posts?tags=11"},{"href":"https:\/\/www.biobasedpress.eu\/nl\/wp-json\/wp\/v2\/tribe_events?tags=11"},{"href":"https:\/\/www.biobasedpress.eu\/nl\/wp-json\/wp\/v2\/tec_calendar_embed?tags=11"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}